{"id":2694,"date":"2016-11-05T09:10:00","date_gmt":"2016-11-05T07:10:00","guid":{"rendered":"http:\/\/www.anita-gratzer.net\/ph\/?p=2694"},"modified":"2025-04-14T16:48:41","modified_gmt":"2025-04-14T14:48:41","slug":"tehran-09-10-16","status":"publish","type":"post","link":"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/","title":{"rendered":"Tehran | Iran 09-10.16"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:32.07049%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2695\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p6038\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038.jpg?fit=1596%2C2401\" data-orig-size=\"1596,2401\" data-comments-opened=\"0\" data-image-title=\"K3P6038\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038.jpg?fit=681%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 1 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038-681x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038-681x1024.jpg?strip=info&#038;w=681 681w\" alt=\"\" data-height=\"2401\" data-id=\"2695\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p6038\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038-681x1024.jpg\" data-width=\"1596\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6038-681x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 1 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:31.92638%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2696\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-13-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1.jpg?fit=1280%2C956\" data-orig-size=\"1280,956\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-13-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1.jpg?fit=1024%2C765\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 2 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1-1024x765.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1-1024x765.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1-1024x765.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"956\" data-id=\"2696\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-13-1\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1-1024x765.jpg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-13-1-1024x765.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 2 of 17 in full-screen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2697\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-14\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14.jpg?fit=1296%2C968\" data-orig-size=\"1296,968\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-14\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14.jpg?fit=1024%2C765\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 3 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14-1024x765.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14-1024x765.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14-1024x765.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"968\" data-id=\"2697\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-14\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14-1024x765.jpg\" data-width=\"1296\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-14-1024x765.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 3 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:36.00314%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2698\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-40\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40.jpg?fit=956%2C1280\" data-orig-size=\"956,1280\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-40\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40.jpg?fit=765%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 4 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40-765x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40-765x1024.jpg?strip=info&#038;w=765 765w\" alt=\"\" data-height=\"1280\" data-id=\"2698\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-40\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40-765x1024.jpg\" data-width=\"956\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-40-765x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 4 of 17 in full-screen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:61.93693%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2699\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-57\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57.jpg?fit=956%2C1280\" data-orig-size=\"956,1280\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-57\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57.jpg?fit=765%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 5 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57-765x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57-765x1024.jpg?strip=info&#038;w=765 765w\" alt=\"\" data-height=\"1280\" data-id=\"2699\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-57\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57-765x1024.jpg\" data-width=\"956\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-57-765x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 5 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:38.06307%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2701\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p6040\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040.jpg?fit=2401%2C1596\" data-orig-size=\"2401,1596\" data-comments-opened=\"0\" data-image-title=\"K3P6040\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040.jpg?fit=1024%2C681\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 6 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040-1024x681.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040-1024x681.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040-1024x681.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"1596\" data-id=\"2701\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p6040\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040-1024x681.jpg\" data-width=\"2401\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/K3P6040-1024x681.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 6 of 17 in full-screen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2703\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-25\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25.jpg?fit=1280%2C956\" data-orig-size=\"1280,956\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-25\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25.jpg?fit=1024%2C765\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 7 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25-1024x765.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25-1024x765.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25-1024x765.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"956\" data-id=\"2703\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-25\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25-1024x765.jpg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-25-1024x765.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 7 of 17 in full-screen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2704\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-48-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48.jpg?fit=1280%2C956\" data-orig-size=\"1280,956\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-48\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48.jpg?fit=1024%2C765\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 8 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48-1024x765.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48-1024x765.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48-1024x765.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"956\" data-id=\"2704\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-48-4\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48-1024x765.jpg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-48-1024x765.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 8 of 17 in full-screen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:21.49070%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2705\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-44\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44.jpg?fit=956%2C1280\" data-orig-size=\"956,1280\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-44\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44.jpg?fit=765%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 9 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44-765x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44-765x1024.jpg?strip=info&#038;w=765 765w\" alt=\"\" data-height=\"1280\" data-id=\"2705\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-44\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44-765x1024.jpg\" data-width=\"956\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2020\/11\/FullSizeRender-44-765x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 9 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:43.15714%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"4315\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p5819\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-scaled.jpg?fit=2560%2C1702\" data-orig-size=\"2560,1702\" data-comments-opened=\"0\" data-image-title=\"K3P5819\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-scaled.jpg?fit=1024%2C681\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 10 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-1024x681.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-1024x681.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-1024x681.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"1702\" data-id=\"4315\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p5819\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-1024x681.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5819-1024x681.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 10 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.14358%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"4316\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p5872\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-scaled.jpg?fit=1702%2C2560\" data-orig-size=\"1702,2560\" data-comments-opened=\"0\" data-image-title=\"K3P5872\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-scaled.jpg?fit=681%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 11 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-681x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-681x1024.jpg?strip=info&#038;w=681 681w\" alt=\"\" data-height=\"2560\" data-id=\"4316\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/k3p5872\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-681x1024.jpg\" data-width=\"1702\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2022\/10\/K3P5872-681x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 11 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:16.20857%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5088\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_1978\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1978.jpg?fit=1350%2C2401\" data-orig-size=\"1350,2401\" data-comments-opened=\"0\" data-image-title=\"DSC_1978\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1978.jpg?fit=576%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 12 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1978-576x1024.jpg?strip=info&#038;w=576 576w\" alt=\"\" data-height=\"2401\" data-id=\"5088\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_1978\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1978-576x1024.jpg\" data-width=\"1350\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1978-576x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 12 of 17 in full-screen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5089\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0996\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0996.jpg?fit=1350%2C2401\" data-orig-size=\"1350,2401\" data-comments-opened=\"0\" data-image-title=\"DSC_0996\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0996.jpg?fit=576%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 13 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0996-576x1024.jpg?strip=info&#038;w=576 576w\" alt=\"\" data-height=\"2401\" data-id=\"5089\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0996\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0996-576x1024.jpg\" data-width=\"1350\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0996-576x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 13 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5090\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0472\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0472.jpg?fit=1350%2C2401\" data-orig-size=\"1350,2401\" data-comments-opened=\"0\" data-image-title=\"DSC_0472\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0472.jpg?fit=576%2C1024\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 14 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0472-576x1024.jpg?strip=info&#038;w=576 576w\" alt=\"\" data-height=\"2401\" data-id=\"5090\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0472\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0472-576x1024.jpg\" data-width=\"1350\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0472-576x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 14 of 17 in full-screen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:39.71538%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5091\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0486\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486.jpg?fit=2401%2C1350\" data-orig-size=\"2401,1350\" data-comments-opened=\"0\" data-image-title=\"DSC_0486\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486.jpg?fit=1024%2C576\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 15 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486-1024x576.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486-1024x576.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486-1024x576.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"1350\" data-id=\"5091\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0486\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486-1024x576.jpg\" data-width=\"2401\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0486-1024x576.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 15 of 17 in full-screen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5092\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0948\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948.jpg?fit=2401%2C1350\" data-orig-size=\"2401,1350\" data-comments-opened=\"0\" data-image-title=\"DSC_0948\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948.jpg?fit=1024%2C576\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 16 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948-1024x576.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948-1024x576.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948-1024x576.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"1350\" data-id=\"5092\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/dsc_0948\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948-1024x576.jpg\" data-width=\"2401\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_0948-1024x576.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 16 of 17 in full-screen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:60.28462%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5093\" data-permalink=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-6\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6.jpg?fit=2400%2C1793\" data-orig-size=\"2400,1793\" data-comments-opened=\"0\" data-image-title=\"FullSizeRender-6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6.jpg?fit=1024%2C765\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 17 of 17 in full-screen\" srcset=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6-1024x765.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6-1024x765.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6-1024x765.jpg?strip=info&#038;w=1024 1024w\" alt=\"\" data-height=\"1793\" data-id=\"5093\" data-link=\"http:\/\/www.anita-gratzer.net\/ph\/tehran-09-10-16\/fullsizerender-6\/\" data-url=\"http:\/\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6-1024x765.jpg\" data-width=\"2400\" src=\"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/FullSizeRender-6-1024x765.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Open image 17 of 17 in full-screen\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">The studio was located at the compound of the Austrian embassy. Therefore I could not invite any visitors. On the other hand I was allowed to use the pool of the ambassadors mansion.  Turned out to be a good deal by the daily rise of local temperatures.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The studio was located at the compound of the Austrian embassy. Therefore I could not invite any visitors. On the other hand I was allowed to use the pool of the ambassadors mansion. Turned out to be a good deal by the daily rise of local temperatures.<\/p>\n","protected":false},"author":1,"featured_media":5086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[43],"tags":[],"class_list":["post-2694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-residency"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p53dR0-Hs","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.anita-gratzer.net\/ph\/wp-content\/uploads\/2016\/11\/DSC_1129.jpg?fit=1350%2C2401","_links":{"self":[{"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/posts\/2694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/comments?post=2694"}],"version-history":[{"count":0,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/posts\/2694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/media\/5086"}],"wp:attachment":[{"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/media?parent=2694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/categories?post=2694"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.anita-gratzer.net\/ph\/wp-json\/wp\/v2\/tags?post=2694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}